{"id":17161,"date":"2026-03-10T10:18:55","date_gmt":"2026-03-10T09:18:55","guid":{"rendered":"https:\/\/bbmri.at\/?post_type=news-articles&#038;p=17161"},"modified":"2026-04-15T17:13:28","modified_gmt":"2026-04-15T15:13:28","slug":"neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern","status":"publish","type":"news-articles","link":"https:\/\/bbmri.at\/de\/news-articles\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\/","title":{"rendered":"Neue Qualit\u00e4tsstandards f\u00fcr den Nachweis von cfDNA und Krankheitserregern"},"content":{"rendered":"    <div id=\"main_textblock_b04cff30e3de74ffe538fd0b3a2824c1\" class=\"content-row content-row-main_text\">\n        <div class=\"contentPart-main contentPart-main-main_text trans \">\n            <div class=\"contentPart_inner\">\n                \n                                    <h1 class=\"heading_main_txt HL_main\">\n                        Neuigkeiten zu europ\u00e4ischen Qualit\u00e4tsstandards f\u00fcr Diagnostik, Biobanking und Forschung \u2014 und Beitrag von BBMRI.at                    <\/h1>\n                \n                                    <h3 class=\"subheading_main_txt HL_sub\">\n                        Von pr\u00e4analytischen Leitlinien f\u00fcr cfDNA in Urin und anderen K\u00f6rperfl\u00fcssigkeiten bis hin zum Erregernachweis: BBMRI.at bringt seine Expertise in ISO\/TC 212 und CEN\/TC 140 ein und unterst\u00fctzt damit die Entwicklung von ISO\/CEN-Standards. Dazu z\u00e4hlen die pr\u00e4analytische Probenstandards f\u00fcr cfDNA (k\u00fcrzlich ver\u00f6ffentlicht) sowie ein Standard zur Pathogendetektion (derzeit in Entwicklung).                    <\/h3>\n                \n                                    <div class=\"text_main_text text1624 main_text_margin\">\n                        <pre><strong>K\u00fcrzlich ver\u00f6ffentlicht: ISO-Standard zur Pr\u00e4analytik von cfDNA aus Urin und anderen K\u00f6rperfl\u00fcssigkeiten\r\n\r\n<\/strong><\/pre>\n<p>Der internationale Standard <a href=\"https:\/\/www.iso.org\/obp\/ui\/en\/#iso:std:iso:18704:ed-1:v1:en\">ISO 18704:2025<\/a>\u00a0legt Anforderungen und Empfehlungen f\u00fcr die Sammlung, Handhabung, den Transport, die Verarbeitung und die Lagerung <strong>von Urin und anderen K\u00f6rperfl\u00fcssigkeiten f\u00fcr die Analyse zirkulierender zellfreier DNA (cell-free DNA, cfDNA)<\/strong> fest. Er wurde von <a href=\"https:\/\/www.iso.org\/committee\/54916.html\">ISO\/TC 212\/WG 4<\/a>\u00a0unter Mitwirkung von <a href=\"https:\/\/bbmri.at\/\">BBMRI.at<\/a>\u00a0(vertreten durch Cornelia Stumptner, Medizinische Universit\u00e4t Graz) entwickelt. Der Standard tr\u00e4gt dazu bei, pr\u00e4analytische Variabilit\u00e4t zu minimieren, die Menge und Integrit\u00e4t der cfDNA zu erhalten und eine verl\u00e4ssliche Performance analytischer Methoden zu unterst\u00fctzen.<\/p>\n<p>&nbsp;<\/p>\n<p>Wesentliche pr\u00e4analytische Variablen, die die Probenqualit\u00e4t und damit das Analyseergebnis beeinflussen, \u00a0sind unter anderem: die Vorbereitung der Patient*innen, \u00a0der Probentyp, Zeitpunkt und Methode der Probenahme, Stabilisierungsmethode und -zeitpunkt, Probentransportbedingungen, Art der cfDNA Isolation, sowie Lagertemperatur und -dauer.<\/p>\n<pre><strong>\u00a0<\/strong><\/pre>\n                    <\/div>\n                \n                                    <div class=\"btnBox btnBox_main_text row\">\n                                                    <a href=\"https:\/\/www.iso.org\/obp\/ui\/en\/#iso:std:iso:18704:ed-1:v1:en\" target=\"_blank\" class=\"btnBox_inner_link btnBox_inner_left fl_align_center\">\n                                <span class=\"main_btn_icon\"><\/span>\n                                <span class=\"main_btn_icon_hover\"><\/span>\n                                <span class=\"main_btn_font btnBox_inner\">\uf0d8\tZu ISO 18704:2025, Molekulare in-vitro-diagnostische Untersuchungen \u2014 Spezifikationen f\u00fcr pr\u00e4analytische Prozesse f\u00fcr zellfreie DNA aus Urin und anderen K\u00f6rperfl\u00fcssigkeiten<\/span>\n                            <\/a>\n                        \n                                            <\/div>\n                            <\/div>\n\n\n\n            <div class=\"contentPart-sidebarDummy\"><\/div>\n        <\/div>\n\n    <\/div>\n\n\n    <div id=\"plain_textfieldblock_10dab1155572b06f8aa33ca6e6ac26c3\" class=\"content-row content-row-plain_textfield\">\r\n        <div class=\"contentPart contentPart-main contentPart-main-plain_textfield trans  \">\r\n            <div class=\"contentPart_inner\">\r\n                                    <div class=\"plain_textfield text1624 \">\r\n                        <p><strong>BBMRI.at in Arbeitsgruppen- und Plenarsitzungen von CEN\/TC 140<br \/>\n<\/strong><\/p>\n<p><strong><br \/>\n<\/strong>BBMRI.at (vertreten durch Cornelia Stumptner) bringt seine Expertise in das technische Komitee 140 der Europ\u00e4isches Komitee f\u00fcr Normung &#8211; CEN\/TC 140 &#8211; ein und nahm an der j\u00fcngsten Sitzung der Arbeitsgruppe 3 sowie der Plenarsitzung am Deutschen Institut f\u00fcr Normung (DIN) teil. Ein aktueller Schwerpunkt ist \u201eMolekulare in-vitro-diagnostische Untersuchungen \u2014 Pr\u00e4analytische Prozesse f\u00fcr humane Proben zur Detektion infekti\u00f6ser Erreger \u2014 Viren, Bakterien, Pilze und Parasiten\u201c. Der Standard wird Empfehlungen enthalten, die beitragen, die pr\u00e4analytische Phase f\u00fcr eine robustere Pathogendetektion zu harmonisieren.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Expert*innen arbeiteten zudem an der \u00dcberarbeitung der pr\u00e4analytischen Normenreihe f\u00fcr humane Proben, darunter FFPE-Gewebe (ISO 20166), gefrorenes Gewebe (ISO 20184) und Vollblut (ISO 20186) f\u00fcr die Analyse isolierter DNA\/RNA. Diese Normen wurden urspr\u00fcnglich im Rahmen des <a href=\"https:\/\/www.spidia.eu\/\">EU-Projekts SPIDIA4P<\/a>\u00a0mit CEN entwickelt und sp\u00e4ter als ISO-Standards ver\u00f6ffentlicht; nach dem routinem\u00e4\u00dfigen systematischen Review rund f\u00fcnf Jahre nach Ver\u00f6ffentlichung steht nun eine Aktualisierung an.<\/p>\n<p>&nbsp;<\/p>\n<p>Die j\u00fcngsten Sitzungen von CEN\/TC 140 brachten internationale Expert*innen zusammen, die an harmonisierten Standards f\u00fcr hochwertige Diagnostik, Biobanking und biomedizinische Forschung arbeiten.<\/p>\n                    <\/div>\r\n                            <\/div>\r\n            <div class=\"contentPart-sidebarDummy\"><\/div>\r\n\r\n        <\/div>\r\n    <\/div>\r\n\n\n    <div id=\"img_wideblock_83653b60b44a5450df70125cc3cb4be7\" class=\"content-row content-row-img_wide\">\r\n        <div class=\" contentPart-main contentPart-main-img_wide trans  \">\r\n            <div class=\"contentPart_inner\">\r\n                                <a  class=\"img_link\" >\r\n                                        <img decoding=\"async\" src=\"https:\/\/bbmri.at\/wp-content\/uploads\/2026\/03\/Gruppenbild-CEN-fur-Text-V2.png\" alt=\"\" class=\"contentwidth_img\">\r\n                                            <span class=\"img-capt\"><\/span>\r\n                                    <\/a>\r\n            <\/div>\r\n            <div class=\"contentPart-sidebarDummy\"><\/div>\r\n        <\/div>\r\n    <\/div>\r\n\n\n    <div id=\"plain_textfieldblock_2cb4d27272a3fb94f3e1b3e852b0816e\" class=\"content-row content-row-plain_textfield\">\r\n        <div class=\"contentPart contentPart-main contentPart-main-plain_textfield trans  \">\r\n            <div class=\"contentPart_inner\">\r\n                                    <div class=\"plain_textfield text1624 \">\r\n                        <p>Von hinten nach vorne\/links nach rechts:<br \/>\nG\u00fcnther Kalle, Braun Susanne, Arnold Peter, Riegman Peter H.J., Hermes Bj\u00f6rn, Gut Ivo, Spitzenberger Folker, Schr\u00f6der Ulrike, Stumptner Cornelia, Gut Marta, Lindh Linda, Oelmueller Uwe<\/p>\n                    <\/div>\r\n                            <\/div>\r\n            <div class=\"contentPart-sidebarDummy\"><\/div>\r\n\r\n        <\/div>\r\n    <\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>mit Beitrag von BBMRI.at entwickelt<\/p>\n","protected":false},"featured_media":16710,"template":"","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[157],"class_list":["post-17161","news-articles","type-news-articles","status-publish","has-post-thumbnail","hentry","category-quality-de-news-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neue Qualit\u00e4tsstandards f\u00fcr den Nachweis von cfDNA und Krankheitserregern - BBMRI.at<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bbmri.at\/de\/news-articles\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neue Qualit\u00e4tsstandards f\u00fcr den Nachweis von cfDNA und Krankheitserregern - BBMRI.at\" \/>\n<meta property=\"og:description\" content=\"mit Beitrag von BBMRI.at entwickelt\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bbmri.at\/de\/news-articles\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\/\" \/>\n<meta property=\"og:site_name\" content=\"BBMRI.at\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T15:13:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bbmri.at\/wp-content\/uploads\/2026\/03\/Gruppenbild-CEN-Kachel.png\" \/>\n\t<meta property=\"og:image:width\" content=\"372\" \/>\n\t<meta property=\"og:image:height\" content=\"196\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bbmri.at\\\/de\\\/news-articles\\\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\\\/\",\"url\":\"https:\\\/\\\/bbmri.at\\\/de\\\/news-articles\\\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\\\/\",\"name\":\"Neue Qualit\u00e4tsstandards f\u00fcr den Nachweis von cfDNA und Krankheitserregern - BBMRI.at\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bbmri.at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bbmri.at\\\/de\\\/news-articles\\\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bbmri.at\\\/de\\\/news-articles\\\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bbmri.at\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Gruppenbild-CEN-Kachel.png\",\"datePublished\":\"2026-03-10T09:18:55+00:00\",\"dateModified\":\"2026-04-15T15:13:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bbmri.at\\\/de\\\/news-articles\\\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\\\/#breadcrumb\"},\"inLanguage\":\"de-AT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bbmri.at\\\/de\\\/news-articles\\\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\\\/\\\/bbmri.at\\\/de\\\/news-articles\\\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bbmri.at\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Gruppenbild-CEN-Kachel.png\",\"contentUrl\":\"https:\\\/\\\/bbmri.at\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Gruppenbild-CEN-Kachel.png\",\"width\":372,\"height\":196},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bbmri.at\\\/de\\\/news-articles\\\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/bbmri.at\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neue Qualit\u00e4tsstandards f\u00fcr den Nachweis von cfDNA und Krankheitserregern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bbmri.at\\\/#website\",\"url\":\"https:\\\/\\\/bbmri.at\\\/\",\"name\":\"BBMRI.at\",\"description\":\"Biobanking and BioMolecular resources Research Infrastructure Austria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bbmri.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-AT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neue Qualit\u00e4tsstandards f\u00fcr den Nachweis von cfDNA und Krankheitserregern - BBMRI.at","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bbmri.at\/de\/news-articles\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\/","og_locale":"de_DE","og_type":"article","og_title":"Neue Qualit\u00e4tsstandards f\u00fcr den Nachweis von cfDNA und Krankheitserregern - BBMRI.at","og_description":"mit Beitrag von BBMRI.at entwickelt","og_url":"https:\/\/bbmri.at\/de\/news-articles\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\/","og_site_name":"BBMRI.at","article_modified_time":"2026-04-15T15:13:28+00:00","og_image":[{"width":372,"height":196,"url":"https:\/\/bbmri.at\/wp-content\/uploads\/2026\/03\/Gruppenbild-CEN-Kachel.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bbmri.at\/de\/news-articles\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\/","url":"https:\/\/bbmri.at\/de\/news-articles\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\/","name":"Neue Qualit\u00e4tsstandards f\u00fcr den Nachweis von cfDNA und Krankheitserregern - BBMRI.at","isPartOf":{"@id":"https:\/\/bbmri.at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bbmri.at\/de\/news-articles\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\/#primaryimage"},"image":{"@id":"https:\/\/bbmri.at\/de\/news-articles\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\/#primaryimage"},"thumbnailUrl":"https:\/\/bbmri.at\/wp-content\/uploads\/2026\/03\/Gruppenbild-CEN-Kachel.png","datePublished":"2026-03-10T09:18:55+00:00","dateModified":"2026-04-15T15:13:28+00:00","breadcrumb":{"@id":"https:\/\/bbmri.at\/de\/news-articles\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\/#breadcrumb"},"inLanguage":"de-AT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bbmri.at\/de\/news-articles\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\/"]}]},{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/bbmri.at\/de\/news-articles\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\/#primaryimage","url":"https:\/\/bbmri.at\/wp-content\/uploads\/2026\/03\/Gruppenbild-CEN-Kachel.png","contentUrl":"https:\/\/bbmri.at\/wp-content\/uploads\/2026\/03\/Gruppenbild-CEN-Kachel.png","width":372,"height":196},{"@type":"BreadcrumbList","@id":"https:\/\/bbmri.at\/de\/news-articles\/neue-qualitaetsstandards-fuer-den-nachweis-von-cfdna-und-krankheitserregern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/bbmri.at\/de\/"},{"@type":"ListItem","position":2,"name":"Neue Qualit\u00e4tsstandards f\u00fcr den Nachweis von cfDNA und Krankheitserregern"}]},{"@type":"WebSite","@id":"https:\/\/bbmri.at\/#website","url":"https:\/\/bbmri.at\/","name":"BBMRI.at","description":"Biobanking and BioMolecular resources Research Infrastructure Austria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bbmri.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-AT"}]}},"_links":{"self":[{"href":"https:\/\/bbmri.at\/de\/wp-json\/wp\/v2\/news-articles\/17161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bbmri.at\/de\/wp-json\/wp\/v2\/news-articles"}],"about":[{"href":"https:\/\/bbmri.at\/de\/wp-json\/wp\/v2\/types\/news-articles"}],"version-history":[{"count":6,"href":"https:\/\/bbmri.at\/de\/wp-json\/wp\/v2\/news-articles\/17161\/revisions"}],"predecessor-version":[{"id":17167,"href":"https:\/\/bbmri.at\/de\/wp-json\/wp\/v2\/news-articles\/17161\/revisions\/17167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bbmri.at\/de\/wp-json\/wp\/v2\/media\/16710"}],"wp:attachment":[{"href":"https:\/\/bbmri.at\/de\/wp-json\/wp\/v2\/media?parent=17161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bbmri.at\/de\/wp-json\/wp\/v2\/categories?post=17161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}