{"id":14319,"date":"2025-04-10T12:28:21","date_gmt":"2025-04-10T10:28:21","guid":{"rendered":"https:\/\/bbmri.at\/?post_type=news-articles&#038;p=14319"},"modified":"2025-04-29T19:12:31","modified_gmt":"2025-04-29T17:12:31","slug":"fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken","status":"publish","type":"news-articles","link":"https:\/\/bbmri.at\/de\/news-articles\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\/","title":{"rendered":"Fortschritte bei der Diagnostik von Milztumoren bei Hunden durch Analyse von miRNA unter Verwendung von Proben aus veterin\u00e4rmedizinischen Biobanken"},"content":{"rendered":"    <div id=\"main_textblock_badbeeb08dbad1b3629b4d86ec04bbf0\" class=\"content-row content-row-main_text\">\n        <div class=\"contentPart-main contentPart-main-main_text trans \">\n            <div class=\"contentPart_inner\">\n                                    <h3 class=\"sub-subheading_main_txt sub-subhl\">\n                        BBMRI.at Publikation                    <\/h3>\n                \n                                    <h1 class=\"heading_main_txt HL_main\">\n                        Fortschritte bei der Diagnostik von Milztumoren bei Hunden durch Analyse von miRNA unter Verwendung von Proben aus veterin\u00e4rmedizinischen Biobanken                    <\/h1>\n                \n                                    <h3 class=\"subheading_main_txt HL_sub\">\n                        Forschende der Universit\u00e4t Guelph in Kanada und des BBMRI.at Partners, der Veterin\u00e4rmedizinischen Universit\u00e4t Wien, zeigten, dass miRNA-Analysen zur pr\u00e4ziseren Diagnostik von Milzerkrankungen bei Hunden beitragen k\u00f6nnen.  F\u00fcr die Durchf\u00fchrung dieser Studie war es notwendig Proben aus zwei Biobanken  \u2013 der VetBiobank Wien und der Veterinary Biobank des Ontario Veterinary College \u2013 zu beziehen, um eine ausreichend gro\u00dfe Anzahl an Proben untersuchen zu k\u00f6nnen.                     <\/h3>\n                \n                                    <div class=\"text_main_text text1624 main_text_margin\">\n                        <pre>Herausforderungen bei der Diagnose von Milztumoren\r\n\r\n<\/pre>\n<p>Milztumore, die aus gutartigen oder b\u00f6sartigen L\u00e4sionen entstehen k\u00f6nnen, treten bei Hunden h\u00e4ufig auf und erfordern sehr unterschiedliche klinischen Ma\u00dfnahmen. Gutartige Tumore, wie z.B. Milzh\u00e4matome und nodul\u00e4re Hyperplasien, sind nicht-krebsartige Ansammlungen von geronnenem Blut. Sie k\u00f6nnen operativ in kurativer Absicht entfernt werden. Im Gegensatz dazu stellen b\u00f6sartige L\u00e4sionen, darunter das H\u00e4mangiosarkom, ein h\u00e4ufiger und aggressiver Tumor, eine gro\u00dfe Herausforderung dar, zur\u00fcckzuf\u00fchren auf eine schlechte Prognose und die Schwierigkeit, sie sowohl klinisch als auch histologisch von gutartigen Tumoren zu unterscheiden. Diese Tumore werden oft zuf\u00e4llig oder bei Notf\u00e4llen, die durch ein H\u00e4mabdomen verursacht werden, entdeckt und erfodern \u00a0einen unmittelbaren chirurgischen Eingriff, bei dem ein gro\u00dfer Blutverlust die Operation erschweren kann.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<pre>Bedarf an diagnostischen Point-of-Care-Tests\r\n\r\n<\/pre>\n<p>Ein diagnostischer Point-of-Care-Test k\u00f6nnte wesentlich dazu beitragen, Milztumore zu identifizieren und damit die Behandlungsentscheidung zwischen Operation und Euthanasie zu erleichtern. Die fr\u00fchzeitige Erkennung durch routinem\u00e4\u00dfige Blutuntersuchungen k\u00f6nnte nicht nur Notf\u00e4lle verhindern, sondern auch eine rechtzeitige Behandlung b\u00f6sartiger Tumore erm\u00f6glichen, wodurch sich die \u00dcberlebensrate verbessern k\u00f6nnte. In der veterin\u00e4rmedizinischen Forschung ist die Verf\u00fcgbarkeit von qualitativ hochwertigen Proben mit detaillierten Informationen \u00fcber die Handhabung der Proben und die Krankengeschichte nach wie vor ein limitierender Faktor f\u00fcr die Durchf\u00fchrung von Forschungsprojekten. Um diese Herausforderung zu \u00fcberwinden, wurden Proben aus den veterin\u00e4rmedizinischen Biobanken zweier Universit\u00e4ten verwendet, um ausreichend Probenmaterial f\u00fcr statistisch aussagekr\u00e4ftige Analysen zu erhalten.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<pre>Verwendung von miRNA zur Unterscheidung von Tumortypen\r\n\r\n<\/pre>\n<p>In dieser Studie wurde gezeigt, dass microRNAs (miRNAs) aus Gewebe- und Serumproben zur erfolgreichen Unterscheidung von Milz-H\u00e4mangiosarkomen von anderen Milztumoren und Kontrollen ohne Milztumoren bei Hunden herangezogen werden k\u00f6nnen.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Forscher*innen entwickelten mehrere miRNA-Modelle sowohl f\u00fcr Serum- als auch f\u00fcr Gewebeproben:<\/p>\n<ul>\n<li>Das Modell, das sich auf das Vorkommen von miR-135a-5p, miR-10a, miR-450b, miR-152-3p und miR-126-5p aus Serum st\u00fctzt, erlaubte eine Unterscheidung zwischen Kontrollen, gutartigen Milzgeschw\u00fclsten und H\u00e4mangiosarkomen mit einer Gesamtgenauigkeit von 0,86.<\/li>\n<li>Das Modell, welches das Vorkommen von miR-135a-5p, miR-10a, miR-152-3p und miR-19a-3p zur Unterscheidung von Milztumoren (gutartigen Milztumoren oder H\u00e4mangiosarkomen) nutzt, erreichte eine Genauigkeit von 0,93.<\/li>\n<li>Das Modell f\u00fcr Gewebeproben, basierend auf dem Vorkommen von miR-126-5p, miR-502-3p und miR-452-5p, ergab eine Genauigkeit von 0,96 bei der Unterscheidung zwischen gutartigen Milztumoren und H\u00e4mangiosarkomen und erzielte somit bessere Werte als die entsprechenden Modelle f\u00fcr Serumproben.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<pre>Bedeutung f\u00fcr die Veterin\u00e4rmedizin<\/pre>\n<p>&nbsp;<\/p>\n<p>Die Ergebnisse deuten darauf hin, dass die Messung der Konzentrationen dieser miRNAs Tier\u00e4rzt*innen bei der Diagnose von Milztumoren helfen k\u00f6nnte, um letztlich die Behandlungsentscheidungen zu unterst\u00fctzen und die Prognose f\u00fcr erkrankte Hunde zu verbessern. Weitere Validierungen \u00a0werden noch erforderlich sein, aber diese Studie liefert ein grundlegendes Profil der miRNA-Expression bei H\u00e4mangiosarkomen im Vergleich zu gesunden Hunden und solchen mit anderen Milztumoren, wodurch die M\u00f6glichkeit einer fr\u00fchen Diagnostik gegeben ist.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<pre>M\u00f6glicher Beitrag zur Forschung im Bereich der menschlichen Gesundheit<\/pre>\n<p>&nbsp;<\/p>\n<p>Veterin\u00e4rmedizinische Proben gewinnen zunehmend an Bedeutung, da z.B.der Haushund als aussagekr\u00e4ftiges Modell f\u00fcr den Menschen in der translationalen Krebsforschung anerkannt ist. Sarkome bei Hunden weisen viele Gemeinsamkeiten mit menschlichen Sarkomen auf \u2013 darunter genetische Tumoreigenschaften, molekulare Zielstrukturen, histologisches Erscheinungsbild und das Ansprechen auf konventionelle Therapien. Die Rolle von Mikro-RNAs (miRNAs) bei der Karzinogenese, Zellproliferation, Invasion und Metastasierung ist sowohl beim Menschen, als auch beim Hund gut erforscht.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Homologie der miRNAs zwischen Hund und Mensch unterstreicht die Bedeutung von Haushunden als Modellorganismus und bietet die M\u00f6glichkeit, Forschungsergebnisse zwischen Human- und Veterin\u00e4rmedizin zu teilen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Insgesamt zeigt der Artikel das Potenzial von miRNAs als diagnostischer Marker in der veterin\u00e4rmedizinischen Onkologie auf \u2013 insbesondere f\u00fcr ein verbessertes Management von Milztumoren bei Hunden. Dar\u00fcber hinaus wird die zentrale Rolle veterin\u00e4rmedizinischer Proben und Daten f\u00fcr die Forschung hervorgehoben.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<pre>\u00dcber die VetBiobank Wien<\/pre>\n<p>&nbsp;<\/p>\n<p>Die VetBiobank wurde 2007 an der Veterin\u00e4rmedizinischen Universit\u00e4t Wien gegr\u00fcndete, mit dem Bestreben, biologisches Left-over Material vom Universit\u00e4tscampus zu sichern und lokalen und externen Forschenden aus Wissenschaft und Industrie zug\u00e4ngig zu machen. Vorrangiges Ziel der VetBiobank ist es, eine umfassende Sammlung hochwertiger Tierproben mit \u00a0assoziierten medizinischen und pr\u00e4analytischen Daten aufzubauen. Die Sammlungen bestehen haupts\u00e4chlich aus Tumorgeweben und gesundem Referenzgeweben von Katzen und Hunden sowie einer begrenzten Anzahl von Bioproben anderer Tierarten und Krankheiten, darunter Makaken, Pferde, Schweine und kleine Haustiere.<\/p>\n<p>2014 trat sich die VetBiobank dem\u00a0<a href=\"http:\/\/bbmri.at\/\">BBMRI.at<\/a>\u00a0Konsortium bei, dass die Probenqualit\u00e4t durch die Kontrolle des pr\u00e4analytischen Probenmanagements priorisiert. Seit 2015 werden alle Gewebeproben gem\u00e4\u00df den CEN-Pr\u00e4analytischen Standards 16826: 1-2 und 16827: 1-3, die k\u00fcrzlich in die ISO-Standards \u00fcberf\u00fchrt wurden, gesammelt. Die VetBiobank sammelt auch spezifische Proben f\u00fcr Forschungsprojekte, darunter sowohl Gewebeproben als auch K\u00f6rperfl\u00fcssigkeiten (Plasma, Serum, Urin, Stuhl). Gelegentlich werden Proben aus Tierversuchen archiviert, um die Prinzipien der 3Rs zu unterst\u00fctzen. Die Arbeitsweise der VetBiobank ist im Artikel DOI beschrieben: <a href=\"https:\/\/doi.org\/10.5334\/ojb.60.%0d\">DOI: https:\/\/doi.org\/10.5334\/ojb.60.<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<pre>\r\n<\/pre>\n<pre>\r\n<\/pre>\n                    <\/div>\n                \n                            <\/div>\n\n\n\n            <div class=\"contentPart-sidebarDummy\"><\/div>\n        <\/div>\n\n    <\/div>\n\n\n    <div id=\"img_wideblock_c097c9d4ea8caf73a6c0b81963357462\" class=\"content-row content-row-img_wide\">\r\n        <div class=\" contentPart-main contentPart-main-img_wide trans  \">\r\n            <div class=\"contentPart_inner\">\r\n                                <a  class=\"img_link\" >\r\n                                        <img decoding=\"async\" src=\"https:\/\/bbmri.at\/wp-content\/uploads\/2025\/04\/14_2025-3-Publication-Ingrid-Walter_VM-Bild-gr_DE.jpg\" alt=\"\" class=\"contentwidth_img\">\r\n                                            <span class=\"img-capt\"><\/span>\r\n                                    <\/a>\r\n            <\/div>\r\n            <div class=\"contentPart-sidebarDummy\"><\/div>\r\n        <\/div>\r\n    <\/div>\r\n\n\n    <div id=\"links_downloadsblock_c85e02d69fe20aa65b4c6a2deb5e313a\" class=\"content-row content-row-links_downloads  \">\r\n        <div class=\"contentPart-main contentPart-main-links_downloads trans \">\r\n            <div class=\"contentPart_inner contentPart_inner-links_downloads  flex_col\">\r\n                                    <div class=\"linkBox column\">\r\n                                                                                    <div class=\"links_inner\">\r\n                                    <div class=\"btnBox\">\r\n                                        <a href=\"https:\/\/journals.sagepub.com\/doi\/full\/10.1177\/03009858251317466\" target=\"_blank\" class=\"btnBox_inner_link btnBox_links_inner_left flex\">\r\n                                            <span class=\"main_btn_icon main_btn_icon_links_downloads\"><\/span>\r\n                                            <span class=\"main_btn_icon_hover main_btn_icon_hover_downloads\"><\/span>\r\n                                            <span class=\"main_btn_font btnBox_inner\">Publikation (SageJournals)<\/span>\r\n                                        <\/a>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                                                                                <div class=\"links_inner\">\r\n                                    <div class=\"btnBox\">\r\n                                        <a href=\"https:\/\/bbmri.at\/wp-content\/uploads\/2024\/09\/ludwig-et-al-2025-micrornas-in-serum-and-tissue-can-differentiate-splenic-hemangiosarcoma-from-other-splenic-masses-in.pdf\" target=\"_blank\" class=\"btnBox_inner_link btnBox_links_inner_left flex\">\r\n                                            <span class=\"main_btn_icon main_btn_icon_links_downloads\"><\/span>\r\n                                            <span class=\"main_btn_icon_hover main_btn_icon_hover_downloads\"><\/span>\r\n                                            <span class=\"main_btn_font btnBox_inner\">Gesamte Publikation (PDF)<\/span>\r\n                                        <\/a>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                                                                                <div class=\"links_inner\">\r\n                                    <div class=\"btnBox\">\r\n                                        <a href=\"https:\/\/directory.bbmri-eric.eu\/ERIC\/directory\/#\/biobank\/bbmri-eric:ID:AT_VET?Countries=AT\" target=\"_blank\" class=\"btnBox_inner_link btnBox_links_inner_left flex\">\r\n                                            <span class=\"main_btn_icon main_btn_icon_links_downloads\"><\/span>\r\n                                            <span class=\"main_btn_icon_hover main_btn_icon_hover_downloads\"><\/span>\r\n                                            <span class=\"main_btn_font btnBox_inner\">VetBiobank Kollektionen anzeigen<\/span>\r\n                                        <\/a>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                                        <\/div>\r\n                \r\n\r\n\r\n                            <\/div>\r\n\r\n            <div class=\"contentPart-sidebarDummy\"><\/div>\r\n\r\n        <\/div>\r\n    <\/div>\r\n","protected":false},"excerpt":{"rendered":"<p>BBMRI.at Publikation \u00fcber die Differenzierung von Milztumoren bei Hunden<\/p>\n","protected":false},"featured_media":14213,"template":"","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[149,159],"class_list":["post-14319","news-articles","type-news-articles","status-publish","has-post-thumbnail","hentry","category-news-de","category-publication-de-news-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fortschritte bei der Diagnostik von Milztumoren bei Hunden durch Analyse von miRNA unter Verwendung von Proben aus veterin\u00e4rmedizinischen Biobanken - BBMRI.at<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bbmri.at\/de\/news-articles\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fortschritte bei der Diagnostik von Milztumoren bei Hunden durch Analyse von miRNA unter Verwendung von Proben aus veterin\u00e4rmedizinischen Biobanken - BBMRI.at\" \/>\n<meta property=\"og:description\" content=\"BBMRI.at Publikation \u00fcber die Differenzierung von Milztumoren bei Hunden\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bbmri.at\/de\/news-articles\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\/\" \/>\n<meta property=\"og:site_name\" content=\"BBMRI.at\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T17:12:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bbmri.at\/wp-content\/uploads\/2025\/04\/14_2025-3-Publication-Ingrid-Walter_VM-Bild-teaser.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"313\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bbmri.at\\\/de\\\/news-articles\\\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\\\/\",\"url\":\"https:\\\/\\\/bbmri.at\\\/de\\\/news-articles\\\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\\\/\",\"name\":\"Fortschritte bei der Diagnostik von Milztumoren bei Hunden durch Analyse von miRNA unter Verwendung von Proben aus veterin\u00e4rmedizinischen Biobanken - BBMRI.at\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bbmri.at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bbmri.at\\\/de\\\/news-articles\\\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bbmri.at\\\/de\\\/news-articles\\\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bbmri.at\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/14_2025-3-Publication-Ingrid-Walter_VM-Bild-teaser.jpg\",\"datePublished\":\"2025-04-10T10:28:21+00:00\",\"dateModified\":\"2025-04-29T17:12:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bbmri.at\\\/de\\\/news-articles\\\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\\\/#breadcrumb\"},\"inLanguage\":\"de-AT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bbmri.at\\\/de\\\/news-articles\\\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\\\/\\\/bbmri.at\\\/de\\\/news-articles\\\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bbmri.at\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/14_2025-3-Publication-Ingrid-Walter_VM-Bild-teaser.jpg\",\"contentUrl\":\"https:\\\/\\\/bbmri.at\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/14_2025-3-Publication-Ingrid-Walter_VM-Bild-teaser.jpg\",\"width\":313,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bbmri.at\\\/de\\\/news-articles\\\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/bbmri.at\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fortschritte bei der Diagnostik von Milztumoren bei Hunden durch Analyse von miRNA unter Verwendung von Proben aus veterin\u00e4rmedizinischen Biobanken\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bbmri.at\\\/#website\",\"url\":\"https:\\\/\\\/bbmri.at\\\/\",\"name\":\"BBMRI.at\",\"description\":\"Biobanking and BioMolecular resources Research Infrastructure Austria\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bbmri.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-AT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fortschritte bei der Diagnostik von Milztumoren bei Hunden durch Analyse von miRNA unter Verwendung von Proben aus veterin\u00e4rmedizinischen Biobanken - BBMRI.at","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bbmri.at\/de\/news-articles\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\/","og_locale":"de_DE","og_type":"article","og_title":"Fortschritte bei der Diagnostik von Milztumoren bei Hunden durch Analyse von miRNA unter Verwendung von Proben aus veterin\u00e4rmedizinischen Biobanken - BBMRI.at","og_description":"BBMRI.at Publikation \u00fcber die Differenzierung von Milztumoren bei Hunden","og_url":"https:\/\/bbmri.at\/de\/news-articles\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\/","og_site_name":"BBMRI.at","article_modified_time":"2025-04-29T17:12:31+00:00","og_image":[{"width":313,"height":180,"url":"https:\/\/bbmri.at\/wp-content\/uploads\/2025\/04\/14_2025-3-Publication-Ingrid-Walter_VM-Bild-teaser.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bbmri.at\/de\/news-articles\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\/","url":"https:\/\/bbmri.at\/de\/news-articles\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\/","name":"Fortschritte bei der Diagnostik von Milztumoren bei Hunden durch Analyse von miRNA unter Verwendung von Proben aus veterin\u00e4rmedizinischen Biobanken - BBMRI.at","isPartOf":{"@id":"https:\/\/bbmri.at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bbmri.at\/de\/news-articles\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\/#primaryimage"},"image":{"@id":"https:\/\/bbmri.at\/de\/news-articles\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\/#primaryimage"},"thumbnailUrl":"https:\/\/bbmri.at\/wp-content\/uploads\/2025\/04\/14_2025-3-Publication-Ingrid-Walter_VM-Bild-teaser.jpg","datePublished":"2025-04-10T10:28:21+00:00","dateModified":"2025-04-29T17:12:31+00:00","breadcrumb":{"@id":"https:\/\/bbmri.at\/de\/news-articles\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\/#breadcrumb"},"inLanguage":"de-AT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bbmri.at\/de\/news-articles\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\/"]}]},{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/bbmri.at\/de\/news-articles\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\/#primaryimage","url":"https:\/\/bbmri.at\/wp-content\/uploads\/2025\/04\/14_2025-3-Publication-Ingrid-Walter_VM-Bild-teaser.jpg","contentUrl":"https:\/\/bbmri.at\/wp-content\/uploads\/2025\/04\/14_2025-3-Publication-Ingrid-Walter_VM-Bild-teaser.jpg","width":313,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/bbmri.at\/de\/news-articles\/fortschritte-bei-der-diagnostik-von-milztumoren-bei-hunden-durch-analyse-von-mirna-aus-proben-veterinaermedizinischer-biobanken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/bbmri.at\/de\/"},{"@type":"ListItem","position":2,"name":"Fortschritte bei der Diagnostik von Milztumoren bei Hunden durch Analyse von miRNA unter Verwendung von Proben aus veterin\u00e4rmedizinischen Biobanken"}]},{"@type":"WebSite","@id":"https:\/\/bbmri.at\/#website","url":"https:\/\/bbmri.at\/","name":"BBMRI.at","description":"Biobanking and BioMolecular resources Research Infrastructure Austria","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bbmri.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-AT"}]}},"_links":{"self":[{"href":"https:\/\/bbmri.at\/de\/wp-json\/wp\/v2\/news-articles\/14319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bbmri.at\/de\/wp-json\/wp\/v2\/news-articles"}],"about":[{"href":"https:\/\/bbmri.at\/de\/wp-json\/wp\/v2\/types\/news-articles"}],"version-history":[{"count":7,"href":"https:\/\/bbmri.at\/de\/wp-json\/wp\/v2\/news-articles\/14319\/revisions"}],"predecessor-version":[{"id":14381,"href":"https:\/\/bbmri.at\/de\/wp-json\/wp\/v2\/news-articles\/14319\/revisions\/14381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bbmri.at\/de\/wp-json\/wp\/v2\/media\/14213"}],"wp:attachment":[{"href":"https:\/\/bbmri.at\/de\/wp-json\/wp\/v2\/media?parent=14319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bbmri.at\/de\/wp-json\/wp\/v2\/categories?post=14319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}